{"id":1629,"date":"2024-06-26T16:39:49","date_gmt":"2024-06-26T14:39:49","guid":{"rendered":"https:\/\/amoinvitar.com\/store\/?post_type=product&#038;p=1629"},"modified":"2026-09-01T13:34:43","modified_gmt":"2026-09-01T11:34:43","slug":"lista-de-regalos","status":"publish","type":"product","link":"https:\/\/amoinvitar.com\/store\/producto\/lista-de-regalos\/","title":{"rendered":"Complemento &#8211; Lista de regalos simb\u00f3lica para invitaci\u00f3n web"},"content":{"rendered":"<h4 style=\"color: #70ac98;margin-bottom: 1px;margin-top: 2px\"><strong>Ver modelo de muestra:<\/strong><\/h4>\n<p><a class=\"button\" style=\"margin: 0px 0px 5px 0px\" href=\"https:\/\/amoinvitar.com\/demo\/lista-de-regalos\/\" target=\"_blank\" rel=\"noopener\">Ver Lista de Regalos<\/a><\/p>\n<hr \/>\n<h4>Caracter\u00edsticas principales<\/h4>\n<p>Una lista de regalos para agregar a todos los modelos de Invitaci\u00f3n Web, como una alternativa a las listas de regalos f\u00edsicos que ofrecen algunas tiendas de compra online. Con est\u00e1 opci\u00f3n, los invitados acceder\u00e1n desde un bot\u00f3n a esta lista con productos o servicios con un valor simb\u00f3lico, para que puedas recibir el dinero directamente en tu cuenta con un bot\u00f3n para ver los datos bancarios (transferencia, Bizum, etc.) o un link de pago directo (seg\u00fan disponibilidad de la entidad bancaria o billetera virtual).<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/amoinvitar.com\/img\/responsive.png\" alt=\"responsive-icon\" width=\"64\" height=\"64\" title=\"\"><br \/>\nCompatible con todos los dispositivos<\/p>\n<p><a class=\"button\" href=\"https:\/\/wa.me\/message\/57HQCKAMGELDG1\" rel=\"noopener\">CONTACTANOS Y TE ASESORAMOS<\/a><\/p>\n<p>\u00a0<\/p>\n<hr \/>\n<h2>Preguntas frecuentes<\/h2>\n<h3 style=\"color: #70ac98\">\u00bfC\u00f3mo contrato la invitaci\u00f3n?<\/h3>\n<p>Es muy f\u00e1cil: 1) eliges el modelo, realizas la compra online y te enviaremos el acceso al panel de administraci\u00f3n. 2) Nos env\u00edas los datos y fotos desde nuestro panel, para que dise\u00f1emos la invitaci\u00f3n. 3) Podr\u00e1s compartir el link de la invitaci\u00f3n con todas las personas que quieras que asistan al evento con solo un clic.<\/p>\n<h3 style=\"color: #70ac98\">\u00bfCu\u00e1l es la diferencia entre la Invitaci\u00f3n Web y el Save The Date?<\/h3>\n<p>La Invitaci\u00f3n Web es un sitio online con el mismo fin que una invitaci\u00f3n tradicional en papel, pero con funciones ampliadas, donde el invitado podr\u00e1 confirmar su asistencia online con un clic, agendar la fecha, ver las indicaciones en Maps y mucho m\u00e1s. Por otro lado, el Save The Date, es un adelanto para anunciar a los invitados el evento, para que vayan agendando la fecha, previo a la invitaci\u00f3n formal. Tambi\u00e9n se puede usar para recordar a los invitados la fecha unos d\u00edas previos al evento y con nuestra opci\u00f3n Web, podr\u00e1s tener un Save The Date interactivo.<\/p>\n<h3 style=\"color: #70ac98\">\u00bfSe pueden personalizar a\u00fan m\u00e1s?<\/h3>\n<p>Si, puedes optar por quitar secciones que no vas a usar y no tiene costo adicional. Tambi\u00e9n puedes agregar secciones que est\u00e9n en otros modelos, e incluso podemos dise\u00f1arte un modelo a medida con los colores, tipograf\u00eda y m\u00f3dulos que se adapten mejor a tus gustos. Algunas modificaciones no tienen costo, otras si tienen costo adicional. Te invitamos a consultarnos.<\/p>\n<h3 style=\"color: #70ac98\">\u00bfC\u00f3mo les env\u00edo las fotos y textos para personalizar?<\/h3>\n<p>Con la invitaci\u00f3n web vas a recibir un panel de administraci\u00f3n donde vas a poder completar los datos y enviarnos las fotos y videos para que podamos dise\u00f1ar y personalizar tu invitaci\u00f3n. Tambi\u00e9n desde el panel vas a poder enviar la invitaci\u00f3n con el bot\u00f3n para compartir o copiar el link.<\/p>\n<h3 style=\"color: #70ac98\">\u00bfEl link de la invitaci\u00f3n web lleva mi nombre?<\/h3>\n<p>Si, el link de la Invitaci\u00f3n Web o el Save The Date Web se personaliza con tu nombre o el nombre de la pareja y se ver\u00e1 as\u00ed: <strong>amoinvitar.com\/tunombre<\/strong>.<\/p>\n<h3 style=\"color: #70ac98\">\u00bfC\u00f3mo me entero qui\u00e9n confirm\u00f3 asistencia o respondi\u00f3 a las preferencias?<\/h3>\n<p>En el panel de administraci\u00f3n incluido vas a poder acceder a la lista de invitados que respondieron a la invitaci\u00f3n, la lista de canciones sugeridas, las opciones que hayan respondido, etc. Podr\u00e1s ver los datos online o descargar la lista definitiva de invitados en Excel.<\/p>\n<h3 style=\"color: #70ac98\">\u00bfEn cu\u00e1nto tiempo est\u00e1 lista la invitaci\u00f3n?<\/h3>\n<p>La personalizaci\u00f3n y puesta online de la invitaci\u00f3n web demora de 1 a 2 d\u00edas h\u00e1biles desde el momento que nos env\u00edas la totalidad de los archivos y textos personalizados. Si solicitas modificaciones o agregas secciones no incluidas en el modelo, puede demorar un poco m\u00e1s en estar lista. Para creaci\u00f3n de una invitaci\u00f3n con dise\u00f1o, colores y secciones \u00aba medida\u00bb, la demora en la puesta online se puede extender de 7 a 10 d\u00edas h\u00e1biles.<\/p>\n<h3 style=\"color: #70ac98\">\u00bfHay un l\u00edmite de invitados?<\/h3>\n<p>En absoluto, podr\u00e1s enviar la invitaci\u00f3n a todos los invitados que gustes, ya que ninguna de nuestras invitaciones tiene l\u00edmites o cantidad de invitados.<\/p>\n<h3 style=\"color: #70ac98\">A\u00fan me faltan algunos datos del evento \u00bfpuedo comprarla igual?<\/h3>\n<p>\u00a1Claro! puedes comprar la invitaci\u00f3n ahora y nos env\u00edas los datos cuando ya tengas todo confirmado. Cont\u00e1ctanos y te asesoramos.<\/p>\n<p>\u00a0<\/p>\n<hr \/>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ver modelo de muestra: Ver Lista de Regalos Caracter\u00edsticas principales Una lista de regalos para agregar a todos los modelos de Invitaci\u00f3n Web, como una alternativa a las listas de regalos f\u00edsicos que ofrecen algunas tiendas de compra online. Con est\u00e1 opci\u00f3n, los invitados acceder\u00e1n desde un bot\u00f3n a esta lista con productos o servicios [&hellip;]<\/p>\n","protected":false},"featured_media":2081,"template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[69],"product_cat":[80,81,82,101,84,79,19,18,16],"product_tag":[35,26,27,31,38,37,25,30,33,34,29,39,32,28],"class_list":["post-1629","product","type-product","status-publish","has-post-thumbnail","product_brand-amo-invitar","product_cat-invitaciones-para-cumple","product_cat-invitaciones-para-bautizo","product_cat-invitaciones-para-comunion","product_cat-invitaciones-para-eventos","product_cat-invitaciones-para-eventos-infantiles","product_cat-invitaciones-para-graduacion","product_cat-invitaciones-para-mis-15","product_cat-invitaciones-para-bodas","product_cat-sin-categorizar","product_tag-15-anos","product_tag-boda","product_tag-casamiento","product_tag-civil","product_tag-dulces-15","product_tag-fiesta-de-15","product_tag-invitacion-web","product_tag-invitation","product_tag-novia","product_tag-novios","product_tag-save-the-date","product_tag-sweet-15","product_tag-tarjeta","product_tag-wedding","desktop-align-left","tablet-align-left","mobile-align-left","ast-product-gallery-layout-horizontal-slider","ast-product-gallery-with-no-image","ast-product-tabs-layout-horizontal","first","instock","sale","virtual","purchasable","product-type-simple"],"exclude_global_add_ons":[],"addons":[],"uagb_featured_image_src":{"full":["https:\/\/amoinvitar.com\/store\/wp-content\/uploads\/2024\/06\/banner-lista-de-regalos-store.jpg",1800,1200,false],"thumbnail":["https:\/\/amoinvitar.com\/store\/wp-content\/uploads\/2024\/06\/banner-lista-de-regalos-store-150x150.jpg",150,150,true],"medium":["https:\/\/amoinvitar.com\/store\/wp-content\/uploads\/2024\/06\/banner-lista-de-regalos-store-300x200.jpg",300,200,true],"medium_large":["https:\/\/amoinvitar.com\/store\/wp-content\/uploads\/2024\/06\/banner-lista-de-regalos-store-768x512.jpg",768,512,true],"large":["https:\/\/amoinvitar.com\/store\/wp-content\/uploads\/2024\/06\/banner-lista-de-regalos-store-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/amoinvitar.com\/store\/wp-content\/uploads\/2024\/06\/banner-lista-de-regalos-store-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/amoinvitar.com\/store\/wp-content\/uploads\/2024\/06\/banner-lista-de-regalos-store.jpg",1800,1200,false],"woocommerce_thumbnail":["https:\/\/amoinvitar.com\/store\/wp-content\/uploads\/2024\/06\/banner-lista-de-regalos-store-300x225.jpg",300,225,true],"woocommerce_single":["https:\/\/amoinvitar.com\/store\/wp-content\/uploads\/2024\/06\/banner-lista-de-regalos-store-600x400.jpg",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/amoinvitar.com\/store\/wp-content\/uploads\/2024\/06\/banner-lista-de-regalos-store-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"hernansnow","author_link":"https:\/\/amoinvitar.com\/store\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Ver modelo de muestra: Ver Lista de Regalos Caracter\u00edsticas principales Una lista de regalos para agregar a todos los modelos de Invitaci\u00f3n Web, como una alternativa a las listas de regalos f\u00edsicos que ofrecen algunas tiendas de compra online. Con est\u00e1 opci\u00f3n, los invitados acceder\u00e1n desde un bot\u00f3n a esta lista con productos o servicios&hellip;","_links":{"self":[{"href":"https:\/\/amoinvitar.com\/store\/wp-json\/wp\/v2\/product\/1629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amoinvitar.com\/store\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/amoinvitar.com\/store\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amoinvitar.com\/store\/wp-json\/wp\/v2\/media\/2081"}],"wp:attachment":[{"href":"https:\/\/amoinvitar.com\/store\/wp-json\/wp\/v2\/media?parent=1629"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/amoinvitar.com\/store\/wp-json\/wp\/v2\/product_brand?post=1629"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/amoinvitar.com\/store\/wp-json\/wp\/v2\/product_cat?post=1629"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/amoinvitar.com\/store\/wp-json\/wp\/v2\/product_tag?post=1629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}